{"id":68743,"date":"2019-10-22T17:43:15","date_gmt":"2019-10-22T22:43:15","guid":{"rendered":"https:\/\/radiowebmx.com\/nota\/?p=68743"},"modified":"2019-10-22T17:43:15","modified_gmt":"2019-10-22T22:43:15","slug":"cecytem-clave-del-progreso-en-michoacan-humberto-gonzalez","status":"publish","type":"post","link":"https:\/\/radiowebmx.com\/nota\/cecytem-clave-del-progreso-en-michoacan-humberto-gonzalez\/","title":{"rendered":"CECyTEM clave del progreso en Michoac\u00e1n: Humberto Gonz\u00e1lez"},"content":{"rendered":"<p>A 28 a\u00f1os de la fundaci\u00f3n del Colegio de Estudios Cient\u00edficos y Tecnol\u00f3gicos del Estado de Michoac\u00e1n (CECyTEM) plantel 1 en Penjamillo, el diputado integrante del Grupo Parlamentario del Partido de la Revoluci\u00f3n Democr\u00e1tica en la LXXIV Legislatura Local, Humberto Gonz\u00e1lez Villag\u00f3mez reconoci\u00f3 la gran labor de este subsistema que ha formado j\u00f3venes exitosos, competitivos y de clase mundial.<\/p>\n<p>Durante el evento conmemorativo por su 28 aniversario, el legislador por el distrito de Puru\u00e1ndiro felicit\u00f3 y reconoci\u00f3 la labor de la comunidad estudiantil, docentes, personal administrativo y directivo del plantel Penjamillo, quienes durante 15 a\u00f1os han sido reconocidos por sus docentes y estudiantes a nivel nacional.<\/p>\n<p>Tras agradecer la invitaci\u00f3n al evento al licenciado Ram\u00f3n G\u00f3mez Ceja, el diputado perredista reconoci\u00f3 que el CECyTEM es clave en el progreso de Michoac\u00e1n, \u201cha simbolizado mucho para el sector educativo por eso reconozco tambi\u00e9n al doctor Jos\u00e9 Hern\u00e1ndez, director general de esta instituci\u00f3n y a toda la familia de este plantel, el cual ha obtenido premios de manera consecutiva, a trav\u00e9s de los maestros y estudiantes diversos reconocimientos\u201d.<\/p>\n<p>Manifest\u00f3 su respaldo a los 93 planteles que hay en Michoac\u00e1n, subsistema que ha dado la cara por la educaci\u00f3n media superior en el pa\u00eds, ya que siempre se han mantenido por arriba de los indicadores por eficiencia terminal, por arriba de otras instituciones.<\/p>\n<p>Humberto Gonz\u00e1lez llam\u00f3 a los padres de familia y autoridades escolares a redoblar esfuerzos para seguir manteniendo el nombre y prestigio de la instituci\u00f3n, al formar grandes profesionales quienes son clave en la transformaci\u00f3n y progreso de Michoac\u00e1n y del pa\u00eds.<\/p>\n<p>\u201cDebemos estar muy orgullosos todos de esta instituci\u00f3n, los premios, reconocimientos y logros alcanzados con excelencia en las olimpiadas nacionales, jornadas acad\u00e9micas, que caracteriza al CECYTEM, es un compromiso para todos, debemos fortalecer a esta instituci\u00f3n\u201d.<\/p>\n<p>Cabe se\u00f1alar que durante el evento se entregaron reconocimiento a los alumnos m\u00e1s destacados, docentes y personal, en el caso de los estudiantes, se destac\u00f3 a los que realizaron declamaci\u00f3n en oratoria, poes\u00eda y se realiz\u00f3 el corte de list\u00f3n.<\/p>\n<p>Adem\u00e1s de felicitarlos por el aniversario, el diputado integrante del Grupo Parlamentario del PRD en el Congreso del Estado, se comprometi\u00f3 en apoyar en distintas gestiones al Plantel de Penjamillo, adem\u00e1s de acompa\u00f1ar en los docentes en las solicitudes para que se les fortalezca con un mayor presupuesto para el siguiente ejercicio fiscal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 28 a\u00f1os de la fundaci\u00f3n del Colegio de Estudios Cient\u00edficos y Tecnol\u00f3gicos del Estado de Michoac\u00e1n (CECyTEM) plantel 1 en Penjamillo, el diputado integrante del Grupo Parlamentario del Partido de la Revoluci\u00f3n Democr\u00e1tica en la LXXIV Legislatura Local, Humberto Gonz\u00e1lez Villag\u00f3mez reconoci\u00f3 la gran labor de este subsistema que ha formado j\u00f3venes exitosos, competitivos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":68744,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-68743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/68743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/comments?post=68743"}],"version-history":[{"count":1,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/68743\/revisions"}],"predecessor-version":[{"id":68745,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/68743\/revisions\/68745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/media\/68744"}],"wp:attachment":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/media?parent=68743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/categories?post=68743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/tags?post=68743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}