{"id":20554,"date":"2015-12-27T12:46:06","date_gmt":"2015-12-27T18:46:06","guid":{"rendered":"https:\/\/radiowebmx.com\/nota\/?p=20554"},"modified":"2015-12-27T12:46:06","modified_gmt":"2015-12-27T18:46:06","slug":"con-politicas-eficaces-silvano-aureoles-conejo-es-el-principal-aliado-de-las-mujeres-michoacanas","status":"publish","type":"post","link":"https:\/\/radiowebmx.com\/nota\/con-politicas-eficaces-silvano-aureoles-conejo-es-el-principal-aliado-de-las-mujeres-michoacanas\/","title":{"rendered":"Con pol\u00edticas eficaces, Silvano Aureoles Conejo es el principal aliado de las mujeres michoacanas"},"content":{"rendered":"<p><a href=\"https:\/\/radiowebmx.com\/nota\/wp-content\/uploads\/2015\/12\/92e33efe-14fd-4672-9913-e87f7fd9425d.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-20555\" src=\"https:\/\/radiowebmx.com\/nota\/wp-content\/uploads\/2015\/12\/92e33efe-14fd-4672-9913-e87f7fd9425d.jpg\" alt=\"92e33efe-14fd-4672-9913-e87f7fd9425d\" width=\"591\" height=\"354\" srcset=\"https:\/\/radiowebmx.com\/nota\/wp-content\/uploads\/2015\/12\/92e33efe-14fd-4672-9913-e87f7fd9425d.jpg 591w, https:\/\/radiowebmx.com\/nota\/wp-content\/uploads\/2015\/12\/92e33efe-14fd-4672-9913-e87f7fd9425d-300x180.jpg 300w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><\/a>Desde el inicio de la actual administraci\u00f3n encabezada por Silvano Aureoles Conejo, la Secretar\u00eda de la Mujer y su titular, Fabiola Alan\u00eds S\u00e1mano, apoyaron a las mujeres michoacanas en un ritmo sin precedentes en las \u00faltimas gestiones.<\/p>\n<p>Alan\u00eds S\u00e1mano destac\u00f3 que la presente administraci\u00f3n se caracteriza por un trabajo transversal y eficiente entre todas las dependencias bajo el liderazgo del Gobernador del Estado, porque la aspiraci\u00f3n de todas y todos es que las acciones de gobierno sean integrales en favor de las mujeres.<\/p>\n<p>Recalc\u00f3 que con el apoyo del Gobernador Silvano Aureoles se logr\u00f3 en los primeros 15 d\u00edas de su gobierno el arranque del Programa Palabra de Mujer el cual busca el empoderamiento econ\u00f3mico de las mujeres a trav\u00e9s de apoyos y capacitaci\u00f3n financiera.<\/p>\n<p>En este sentido, se logr\u00f3 firmar un acuerdo con Nacional Financiera en el que las mujeres de la entidad pueden acceder a pr\u00e9stamos econ\u00f3micos con una m\u00ednima tasa de inter\u00e9s y sin muchos requisitos; se dieron tambi\u00e9n capacitaciones a m\u00e1s de mil mujeres en la zona de Tierra Caliente en conjunto con el Conalep; se entregaron recursos para m\u00e1s de 15 proyectos productivos a mujeres de la misma zona y se apoyos de vivienda para mujeres en zona de vulnerabilidad.<\/p>\n<p>Esta es una de muchas acciones a favor de las y los michoacanos que dan a conocer el rostro social de la administraci\u00f3n del Gobernador Silvano Aureoles Conejo de forma eficiente, destac\u00f3 la funcionaria estatal. Asimismo, recalc\u00f3 la petici\u00f3n que en reiteradas ocasiones ha hecho el mandatario estatal para que el Gobierno Federal declare la alerta de g\u00e9nero en todo el territorio estatal.<\/p>\n<p>De esto dio cuenta la presidenta del Instituto Nacional de las Mujeres, Lorena Cruz S\u00e1nchez, quien durante su visita a la entidad reconoci\u00f3 el trabajo del Gobierno Estatal y se dijo \u201csorprendida por las labores realizadas en la dependencia encabezada por el Gobernador del Estado\u201d.<\/p>\n<p>Esto luego de que durante la administraci\u00f3n de Aureoles Conejo la dependencia diera capacitaciones sobre pol\u00edticas p\u00fablicas con Transversalidad de G\u00e9nero a m\u00e1s de 2 mil servidores p\u00fablicos mediante el Programa de Fortalecimiento a la Transversalidad de la Perspectiva de G\u00e9nero.<\/p>\n<p>Por otra parte, en la atenci\u00f3n directa a las mujeres se lograron 2 mil 164 atenciones jur\u00eddicas, mil 211 psicol\u00f3gicas, 446 canalizaciones a otras dependencias y se apoy\u00f3 en el tema de trabajo social a m\u00e1s de 143 mujeres en todo el estado, alcanzando con esto casi 4 mil apoyos a las mujeres michoacanas.<\/p>\n<p>Fabiola Alan\u00eds S\u00e1mano subray\u00f3 que con estas acciones, se comprueba una vez m\u00e1s que Silvano Aureoles Conejo es el principal aliado de las mujeres michoacanas, y que implementar\u00e1 pol\u00edticas p\u00fablicas integrales para atenderlas a lo largo de su administraci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el inicio de la actual administraci\u00f3n encabezada por Silvano Aureoles Conejo, la Secretar\u00eda de la Mujer y su titular, Fabiola Alan\u00eds S\u00e1mano, apoyaron a las mujeres michoacanas en un ritmo sin precedentes en las \u00faltimas gestiones.<\/p>\n","protected":false},"author":1,"featured_media":20555,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,3],"tags":[],"class_list":["post-20554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-gobierno-del-estado-de-michoacan"],"_links":{"self":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/20554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/comments?post=20554"}],"version-history":[{"count":1,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/20554\/revisions"}],"predecessor-version":[{"id":20556,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/20554\/revisions\/20556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/media\/20555"}],"wp:attachment":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/media?parent=20554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/categories?post=20554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/tags?post=20554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}