{"id":12657,"date":"2015-01-12T11:51:10","date_gmt":"2015-01-12T17:51:10","guid":{"rendered":"https:\/\/radiowebmx.com\/nota\/?p=12657"},"modified":"2015-01-12T11:51:10","modified_gmt":"2015-01-12T17:51:10","slug":"a-partir-de-este-lunes-se-pueden-tramitar-en-michoacan-actas-de-nacimiento-de-otros-estados","status":"publish","type":"post","link":"https:\/\/radiowebmx.com\/nota\/a-partir-de-este-lunes-se-pueden-tramitar-en-michoacan-actas-de-nacimiento-de-otros-estados\/","title":{"rendered":"A PARTIR DE ESTE LUNES, SE PUEDEN TRAMITAR EN MICHOAC\u00c1N ACTAS DE NACIMIENTO DE OTROS ESTADOS"},"content":{"rendered":"<p>A partir de este lunes 12 de enero en la Direcci\u00f3n del Registro Civil estatal y en las oficial\u00edas de los municipios, ser\u00e1 posible la expedici\u00f3n de copias certificadas de actas de nacimiento de todos los estados de la Rep\u00fablica Mexicana.<\/p>\n<p>El tr\u00e1mite podr\u00e1 realizarse en Morelia, en el Departamento de Actas For\u00e1neas de la Direcci\u00f3n ubicado en Valent\u00edn G\u00f3mez Far\u00edas No. 525 esquina H\u00e9roes de Nocup\u00e9taro, colonia Industrial, en horario de lunes a viernes, de 08:00 a 14:30 horas, as\u00ed como en las oficial\u00edas del Registro Civil de todos los municipios michoacanos.<\/p>\n<p>Con esta acci\u00f3n, se da cumplimiento al convenio signado entre el Gobierno del Estado y la Secretar\u00eda de Gobernaci\u00f3n federal, para acercar y mejorar de forma oportuna y segura, el servicio a la poblaci\u00f3n originaria de otros estados que tienen su residencia eventual o permanente en Michoac\u00e1n.<\/p>\n<p>Cabe recordar que la interconexi\u00f3n de las bases de datos de los registros civiles de las 32 entidades federativas se debe precisamente, al convenio de coordinaci\u00f3n y colaboraci\u00f3n para implementar la consulta e impresi\u00f3n de actas del estado civil de las personas, firmado por el gobernador del estado, Salvador Jara Guerrero, el pasado lunes 5 de enero.<\/p>\n<p>Dicho convenio fue firmado en la residencia oficial de Los Pinos, teniendo como testigo de honor al presidente de la Rep\u00fablica, Enrique Pe\u00f1a Nieto, con el secretario de Gobernaci\u00f3n, Miguel \u00c1ngel Osorio Chong, as\u00ed como los 31 gobernadores de los dem\u00e1s estados del pa\u00eds y del Distrito Federal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de este lunes 12 de enero en la Direcci\u00f3n del Registro Civil estatal y en las oficial\u00edas de los municipios, ser\u00e1 posible la expedici\u00f3n de copias certificadas de actas de nacimiento de todos los estados de la Rep\u00fablica Mexicana.<\/p>\n","protected":false},"author":1,"featured_media":12658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,9],"tags":[],"class_list":["post-12657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-morelia"],"_links":{"self":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/12657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/comments?post=12657"}],"version-history":[{"count":2,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/12657\/revisions"}],"predecessor-version":[{"id":12660,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/12657\/revisions\/12660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/media\/12658"}],"wp:attachment":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/media?parent=12657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/categories?post=12657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/tags?post=12657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}