{"id":12150,"date":"2014-12-08T12:46:58","date_gmt":"2014-12-08T18:46:58","guid":{"rendered":"https:\/\/radiowebmx.com\/nota\/?p=12150"},"modified":"2014-12-08T12:46:58","modified_gmt":"2014-12-08T18:46:58","slug":"la-pluralidad-politica-se-aprecia-reconoce-y-respeta-en-michoacan-jaime-dario-oseguera","status":"publish","type":"post","link":"https:\/\/radiowebmx.com\/nota\/la-pluralidad-politica-se-aprecia-reconoce-y-respeta-en-michoacan-jaime-dario-oseguera\/","title":{"rendered":"LA PLURALIDAD POL\u00cdTICA SE APRECIA, RECONOCE Y RESPETA EN MICHOAC\u00c1N: JAIME DAR\u00cdO OSEGUERA"},"content":{"rendered":"<p>En Michoac\u00e1n la pluralidad pol\u00edtica se aprecia, reconoce y respeta, afirm\u00f3 el secretario de Gobierno, Jaime Dar\u00edo Oseguera M\u00e9ndez, durante el segundo informe de actividades del diputado federal del Partido de la Revoluci\u00f3n Democr\u00e1tica, Silvano Aureoles Conejo.<\/p>\n<p>Por ello, dijo que las diferencias ideol\u00f3gicas que pueda haber en un estado plural como lo es Michoac\u00e1n, no tienen que ser un lastre en la tarea p\u00fablica; al contrario,\u00a0 las formas distintas de ver el mismo problema, son el gran activo de la pol\u00edtica, la mejor evidencia de lo que necesita Michoac\u00e1n.<\/p>\n<p>El encargado de la pol\u00edtica interna del estado record\u00f3 que el pr\u00f3ximo a\u00f1o habr\u00e1 elecciones, por lo que exhort\u00f3 a todos los aspirantes a ocupar un puesto de elecci\u00f3n popular, no solo a los que ganen sino a todos los que participen, a construir un gobierno de unidad que beneficie a todos los michoacanos.<\/p>\n<p>\u201cTiene que ser una tarea colectiva, todas las voces, todas las versiones, todas las visiones ser\u00e1n necesarias para construir el Michoac\u00e1n que queremos\u201d, se\u00f1al\u00f3 Oseguera M\u00e9ndez.<\/p>\n<p>Al acudir, con la representaci\u00f3n del gobernador Salvador Jara Guerrero, al informe del diputado y presidente de la Mesa Directiva de la C\u00e1mara de Diputados del Congreso de la Uni\u00f3n, extern\u00f3 su respeto y reconocimiento a la tarea legislativa que a nombre de Michoac\u00e1n ha realizado Aureoles Conejo.<\/p>\n<p>\u201cVengo a expresar nuestro reconocimiento por la tarea que vienen haciendo los legisladores michoacanos para traer m\u00e1s recursos, para hacer gestiones, para hacer mejores leyes, para que en resumen los michoacanos estemos bien representados en la C\u00e1mara de Diputados\u201d, indic\u00f3 el funcionario estatal.<\/p>\n<p>El secretario de Gobierno dijo estar convencido de que en la medida que haya diputados federales que consigan recursos para los municipios -sin importar el origen partidista de los ediles- , que legislen para mejorar el sistema pol\u00edtico, el sistema de justicia, el federalismo hacendario, Michoac\u00e1n ser\u00e1 mejor. \u201cEn la medida que haya capacidades colectivas y signos claros de acompa\u00f1amiento pol\u00edtico, en esa medida ser\u00e1 m\u00e1s sencillo lograrlo\u201d, indic\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Michoac\u00e1n la pluralidad pol\u00edtica se aprecia, reconoce y respeta, afirm\u00f3 el secretario de Gobierno, Jaime Dar\u00edo Oseguera M\u00e9ndez, durante el segundo informe de actividades del diputado federal del Partido de la Revoluci\u00f3n Democr\u00e1tica, Silvano Aureoles Conejo.<\/p>\n","protected":false},"author":1,"featured_media":12151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,3],"tags":[],"class_list":["post-12150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-gobierno-del-estado-de-michoacan"],"_links":{"self":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/12150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/comments?post=12150"}],"version-history":[{"count":1,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/12150\/revisions"}],"predecessor-version":[{"id":12152,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/12150\/revisions\/12152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/media\/12151"}],"wp:attachment":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/media?parent=12150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/categories?post=12150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/tags?post=12150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}