{"id":11001,"date":"2014-10-24T14:14:34","date_gmt":"2014-10-24T19:14:34","guid":{"rendered":"https:\/\/radiowebmx.com\/nota\/?p=11001"},"modified":"2014-10-24T14:14:34","modified_gmt":"2014-10-24T19:14:34","slug":"atiende-ayuntamiento-normatividad-ambiental-en-el-municipio","status":"publish","type":"post","link":"https:\/\/radiowebmx.com\/nota\/atiende-ayuntamiento-normatividad-ambiental-en-el-municipio\/","title":{"rendered":"ATIENDE AYUNTAMIENTO NORMATIVIDAD AMBIENTAL EN EL MUNICIPIO"},"content":{"rendered":"<p><a href=\"https:\/\/radiowebmx.com\/nota\/wp-content\/uploads\/2014\/10\/DSC_0157.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-11002\" alt=\"DSC_0157\" src=\"https:\/\/radiowebmx.com\/nota\/wp-content\/uploads\/2014\/10\/DSC_0157.jpg\" width=\"591\" height=\"296\" srcset=\"https:\/\/radiowebmx.com\/nota\/wp-content\/uploads\/2014\/10\/DSC_0157.jpg 591w, https:\/\/radiowebmx.com\/nota\/wp-content\/uploads\/2014\/10\/DSC_0157-300x150.jpg 300w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><\/a>Con el objetivo de lograr la correcta separaci\u00f3n de residuos, alentar entre la ciudadan\u00eda pr\u00e1cticas de cuidado con el medio ambiente y cumplir con las leyes federales y reglamentos municipales en materia de prevenci\u00f3n y gesti\u00f3n integral de los residuos, el Ayuntamiento de Morelia, que preside Wilfrido L\u00e1zaro Medina, implementa con \u00e9xito diversas acciones y programas permanentes de la Direcci\u00f3n de Aseo P\u00fablico.<\/p>\n<p>&nbsp;<\/p>\n<p>Bajo la coordinaci\u00f3n del secretario de Servicios P\u00fablicos Municipales, Iv\u00e1n Mois\u00e9s Rodr\u00edguez Medina, en la dependencia se promueve un Programa de Erradicaci\u00f3n de Tiraderos Clandestinos, tanto en la zona urbana como rural del municipio y en donde se tienen localizados un promedio de 35 dep\u00f3sitos ilegales de botellas de pl\u00e1stico, llantas de veh\u00edculos, animales muertos, colchones, muebles dom\u00e9sticos en general y escombro de empresas constructoras.<\/p>\n<p>&nbsp;<\/p>\n<p>Si en el sitio se detecta evidencia que indique a las autoridades municipales qui\u00e9nes podr\u00edan ser responsables de este mal h\u00e1bito, se procede a levantar un acta administrativa para notificar al infractor de la sanci\u00f3n econ\u00f3mica a la que se har\u00eda acreedor y la cual depende de la reincidencia y otros factores, pero oscila entre uno y 5 mil d\u00edas de salario m\u00ednimo vigente.<\/p>\n<p>&nbsp;<\/p>\n<p>En el mismo sentido, se implementa un Programa para erradicar publicidad en la infraestructura urbana federal, estatal y municipal, con el cual se atienden las vialidades primarias para retirar hojas de papel, principalmente, de postes de metal, madera y cemento, as\u00ed como de cabinas telef\u00f3nicas, sem\u00e1foros y negocios, abonando con ello a la reducci\u00f3n de la contaminaci\u00f3n visual.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s de lo anterior, la Direcci\u00f3n de Aseo realiza continuamente jornadas de limpieza en diferentes colonias de la ciudad, en donde suman voluntades con los vecinos para limpiar calles, lotes bald\u00edos, \u00e1reas verdes, plazas p\u00fablicas y en ocasiones inmuebles abandonados que representan un foco de infecci\u00f3n para los habitantes de los alrededores.<\/p>\n<p>&nbsp;<\/p>\n<p>Los j\u00f3venes que prestan servicio social en la Campa\u00f1a Cero Tolerancia tambi\u00e9n contribuyen a la concientizaci\u00f3n de la poblaci\u00f3n\u00a0para que mantengan limpios los frentes de sus casas y negocios y, con ello, eviten taponamientos de alcantarillas y drenes, ocasionando inundaciones. En visitas casa por casa, los estudiantes entregan infracciones de cortes\u00eda a quienes incumplen con el Reglamento General de Limpieza del municipio.<\/p>\n<p>&nbsp;<\/p>\n<p>Mediante talleres y pl\u00e1ticas que imparten los integrantes del Programa S.O.S. en instituciones educativas de todos los niveles, colonias y comunidades, se instrumentan planes como \u201cMenos Pilas m\u00e1s Conciencia\u201d, \u201cReciclotr\u00f3nicos\u201d,\u00a0<b>\u201c<\/b>No m\u00e1s chicles en el piso\u201d, \u201cRecicloterapia\u201d y \u201cBiocomposta, con lo cuales se abona al impulso de una cultura enfocada en reducir, reusar y reciclar.<\/p>\n<p>&nbsp;<\/p>\n<p>Finalmente, las brigadas de barrido manual atienden diariamente la limpieza de puentes vehiculares, t\u00faneles, arroyo vehicular, guarniciones y banquetas del perif\u00e9rico y principales vialidades de los cuatro sectores de la ciudad, con lo que se cubren 258 mil metros lineales por d\u00eda y que en conjunto con las dem\u00e1s acciones que realiza la dependencia contribuyen a que el Ayuntamiento de Morelia obtenga reconocimientos internacionales como la \u201cEscoba de Oro\u201d en Madrid, Espa\u00f1a y el premio nacional \u201cJumil de Oro\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de lograr la correcta separaci\u00f3n de residuos, alentar entre la ciudadan\u00eda pr\u00e1cticas de cuidado con el medio ambiente y cumplir con las leyes federales y reglamentos municipales en materia de prevenci\u00f3n y gesti\u00f3n integral de los residuos, el Ayuntamiento de Morelia, <\/p>\n","protected":false},"author":1,"featured_media":11002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,9],"tags":[],"class_list":["post-11001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-morelia"],"_links":{"self":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/11001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/comments?post=11001"}],"version-history":[{"count":2,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/11001\/revisions"}],"predecessor-version":[{"id":11004,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/posts\/11001\/revisions\/11004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/media\/11002"}],"wp:attachment":[{"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/media?parent=11001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/categories?post=11001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiowebmx.com\/nota\/wp-json\/wp\/v2\/tags?post=11001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}